{"id":442,"count":1,"description":"","link":"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/","name":"Just Associates","slug":"just-associates","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Just Associates Archives - Digital Transformation of Government Services<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Just Associates Archives - Digital Transformation of Government Services\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/\" \/>\n<meta property=\"og:site_name\" content=\"Digital Transformation of Government Services\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@m2sys\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/\",\"url\":\"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/\",\"name\":\"Just Associates Archives - Digital Transformation of Government Services\",\"isPartOf\":{\"@id\":\"https:\/\/www.m2sys.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Just Associates\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.m2sys.com\/blog\/#website\",\"url\":\"https:\/\/www.m2sys.com\/blog\/\",\"name\":\"Digital Transformation of Government Services\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.m2sys.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.m2sys.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.m2sys.com\/blog\/#organization\",\"name\":\"Digital Transformation of Government Services\",\"url\":\"https:\/\/www.m2sys.com\/blog\/\",\"sameAs\":[\"https:\/\/instagram.com\/m2sys\",\"https:\/\/www.linkedin.com\/company\/m2sys-technology\",\"https:\/\/www.pinterest.com\/m2sys\/\",\"https:\/\/www.youtube.com\/user\/M2SYS\",\"https:\/\/www.facebook.com\/m2sys\",\"https:\/\/twitter.com\/m2sys\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.m2sys.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.m2sys.com\/blog\/wp-content\/uploads\/2017\/12\/m2sys-blog.png\",\"contentUrl\":\"https:\/\/www.m2sys.com\/blog\/wp-content\/uploads\/2017\/12\/m2sys-blog.png\",\"width\":287,\"height\":48,\"caption\":\"Digital Transformation of Government Services\"},\"image\":{\"@id\":\"https:\/\/www.m2sys.com\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Just Associates Archives - Digital Transformation of Government Services","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/","og_locale":"en_US","og_type":"article","og_title":"Just Associates Archives - Digital Transformation of Government Services","og_url":"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/","og_site_name":"Digital Transformation of Government Services","twitter_card":"summary_large_image","twitter_site":"@m2sys","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/","url":"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/","name":"Just Associates Archives - Digital Transformation of Government Services","isPartOf":{"@id":"https:\/\/www.m2sys.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.m2sys.com\/blog\/tag\/just-associates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Just Associates"}]},{"@type":"WebSite","@id":"https:\/\/www.m2sys.com\/blog\/#website","url":"https:\/\/www.m2sys.com\/blog\/","name":"Digital Transformation of Government Services","description":"","publisher":{"@id":"https:\/\/www.m2sys.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.m2sys.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.m2sys.com\/blog\/#organization","name":"Digital Transformation of Government Services","url":"https:\/\/www.m2sys.com\/blog\/","sameAs":["https:\/\/instagram.com\/m2sys","https:\/\/www.linkedin.com\/company\/m2sys-technology","https:\/\/www.pinterest.com\/m2sys\/","https:\/\/www.youtube.com\/user\/M2SYS","https:\/\/www.facebook.com\/m2sys","https:\/\/twitter.com\/m2sys"],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.m2sys.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.m2sys.com\/blog\/wp-content\/uploads\/2017\/12\/m2sys-blog.png","contentUrl":"https:\/\/www.m2sys.com\/blog\/wp-content\/uploads\/2017\/12\/m2sys-blog.png","width":287,"height":48,"caption":"Digital Transformation of Government Services"},"image":{"@id":"https:\/\/www.m2sys.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.m2sys.com\/blog\/wp-json\/wp\/v2\/tags\/442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.m2sys.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.m2sys.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.m2sys.com\/blog\/wp-json\/wp\/v2\/posts?tags=442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}